{"id":15281,"date":"2024-02-14T11:37:40","date_gmt":"2024-02-14T11:37:40","guid":{"rendered":"https:\/\/network-king.net\/una-investigacion-utiliza-microbios-del-suelo-para-alimentar-sensores-iot\/"},"modified":"2024-02-24T11:42:34","modified_gmt":"2024-02-24T11:42:34","slug":"una-investigacion-utiliza-microbios-del-suelo-para-alimentar-sensores-iot","status":"publish","type":"articles","link":"https:\/\/network-king.net\/es\/una-investigacion-utiliza-microbios-del-suelo-para-alimentar-sensores-iot\/","title":{"rendered":"Una investigaci\u00f3n utiliza microbios del suelo para alimentar sensores IoT"},"content":{"rendered":"\n<p>Los microbios que viven en el suelo podr\u00edan ser una fuente de energ\u00eda para los sensores subterr\u00e1neos utilizados en la agricultura de precisi\u00f3n y las infraestructuras sostenibles. La novedad la ha propuesto un equipo de investigadores de la Universidad Northwestern de Estados Unidos, que ha desarrollado una nueva pila de combustible que podr\u00eda convertirse en una alternativa sostenible y renovable a las pilas que utilizan productos qu\u00edmicos t\u00f3xicos e inflamables y que cada vez suponen un problema mayor a la hora de deshacerse de los residuos electr\u00f3nicos.<\/p>\n\n<p>Para probar la nueva pila de combustible, los investigadores la utilizaron para alimentar sensores que miden la humedad del suelo y rastrean el movimiento de los animales. Tambi\u00e9n se utiliz\u00f3 una peque\u00f1a antena para transmitir los datos de los sensores a una estaci\u00f3n base cercana. Los resultados mostraron que la pila de combustible no s\u00f3lo funcionaba en condiciones h\u00famedas y secas, sino que adem\u00e1s ten\u00eda una potencia de salida que superaba en un 120% a tecnolog\u00edas similares.<\/p>\n\n<p>\u00abEl n\u00famero de dispositivos del Internet de las Cosas (IoT) no deja de crecer. Si imaginamos un futuro con billones de estos dispositivos, no podremos alimentarlos todos utilizando litio, metales pesados y materiales t\u00f3xicos peligrosos para el medio ambiente. Necesitamos encontrar alternativas que proporcionen poca energ\u00eda para alimentar una red descentralizada\u00bb, afirma Bill Yen, director del proyecto en la Universidad Northwestern. En la b\u00fasqueda de soluciones, los cient\u00edficos evaluaron pilas de combustible que utilizan microbios especiales para descomponer el suelo y aprovechar este bajo nivel de energ\u00eda para alimentar los sensores. \u00abMientras haya carbono org\u00e1nico en el suelo para que los microbios lo descompongan, la pila de combustible durar\u00e1 indefinidamente\u00bb, a\u00f1ade Yen.<\/p>\n\n<p>Estos microbios est\u00e1n por todas partes, viven en el sol y pueden utilizarse en sistemas de ingenier\u00eda muy sencillos para captar energ\u00eda. Obviamente, no pueden alimentar ciudades enteras, pero pueden ser \u00fatiles para suministrar energ\u00eda a aplicaciones de bajo consumo.<\/p>\n\n<p>\u00c9 o caso da agricultura de precis\u00e3o que, por exemplo, nem sempre podem adotar pain\u00e9is solares em ambientes sujos, pouco expostos aos raios solares ou com pouco espa\u00e7o. Em muitos casos, baterias tamb\u00e9m n\u00e3o s\u00e3o vi\u00e1veis como fonte de energia &#8211; imagine ter de percorrer uma fazenda com centenas de hectares para trocar baterias regularmente. S\u00e3o justamente nessas situa\u00e7\u00f5es que captar energia do ambiente &#8211; ou do solo &#8211; \u00e9 uma \u00f3tima solu\u00e7\u00e3o.<\/p>\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03d73515cbf&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03d73515cbf\" class=\"aligncenter size-full is-resized wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1292\" height=\"716\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/network-king.net\/wp-content\/uploads\/2024\/02\/sensorIoT.jpg\" alt=\"Soil-Powered Computing: Gu&#xED;a del ingeniero para el dise&#xF1;o pr&#xE1;ctico de pilas de combustible microbianas del suelo\" class=\"wp-image-15091\" style=\"width:774px;height:auto\" srcset=\"https:\/\/network-king.net\/wp-content\/uploads\/2024\/02\/sensorIoT.jpg 1292w, https:\/\/network-king.net\/wp-content\/uploads\/2024\/02\/sensorIoT-300x166.jpg 300w, https:\/\/network-king.net\/wp-content\/uploads\/2024\/02\/sensorIoT-1024x567.jpg 1024w, https:\/\/network-king.net\/wp-content\/uploads\/2024\/02\/sensorIoT-768x426.jpg 768w\" sizes=\"(max-width: 1292px) 100vw, 1292px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<p>Seg\u00fan los investigadores, las pilas de combustible microbianas que aprovechan el suelo para funcionar como bater\u00eda aparecieron en 1911. Para funcionar sin interrupci\u00f3n, necesitan mantenerse hidratadas y oxigenadas, un factor complicado cuando se entierran bajo tierra y se utilizan en terrenos secos. Con estos retos en mente, los investigadores trabajaron durante dos a\u00f1os para desarrollar un modelo viable y fiable. El trabajo incluy\u00f3 crear y comparar cuatro versiones diferentes, recopilando datos de rendimiento de cada dise\u00f1o para llegar a la versi\u00f3n final probada en exteriores.<\/p>\n\n<p>El mejor prototipo funcionaba bien tanto en entornos secos como inundados. El secreto de su \u00e9xito se esconde tras su geometr\u00eda. En lugar de un dise\u00f1o tradicional, la mejor pila de combustible tiene un dise\u00f1o perpendicular, hecha de fieltro de carbono (un conductor abundante y barato para capturar los electrones de los microbios), con el \u00e1nodo en posici\u00f3n horizontal sobre la superficie del suelo. El c\u00e1todo, de metal inerte y conductor, se sit\u00faa verticalmente sobre el \u00e1nodo.<\/p>\n\n<p>Aunque todo el dispositivo est\u00e1 enterrado, el dise\u00f1o vertical garantiza que el borde superior est\u00e9 nivelado con la superficie del suelo. Una tapa impresa en 3D en la parte superior del dispositivo evita que caigan residuos en su interior. Y un orificio en la parte superior y una c\u00e1mara de aire vac\u00eda junto al c\u00e1todo permiten un flujo constante de aire.<\/p>\n\n<p>El extremo inferior del c\u00e1todo permanece muy por debajo de la superficie, hidratado en el suelo h\u00famedo circundante incluso cuando la superficie est\u00e1 seca. Parte del c\u00e1todo tambi\u00e9n se ha recubierto con material impermeabilizante para que respire en caso de inundaci\u00f3n. Y tras una posible inundaci\u00f3n, el dise\u00f1o vertical permite que el c\u00e1todo se seque poco a poco, en lugar de todo de golpe.<\/p>\n\n<p>De media, la pila de combustible gener\u00f3 68 veces m\u00e1s energ\u00eda de la necesaria para alimentar los sensores. Tambi\u00e9n era lo bastante robusta para soportar grandes cambios en los niveles de humedad del suelo, desde ligeramente seco (41% de agua en volumen) hasta completamente sumergido.<\/p>\n\n<p>La investigaci\u00f3n de la Universidad Northwestern se ha publicado en la revista <a href=\"https:\/\/dl.acm.org\/doi\/10.1145\/3631410\" target=\"_blank\" rel=\"noreferrer noopener\">Proceedings of the Association for Computing Machinery on Interactive, Mobile, Wearable and Ubiquitous Technologies<\/a>. Los autores del estudio tambi\u00e9n han hecho p\u00fablicos los proyectos, tutoriales y herramientas de simulaci\u00f3n para que puedan ser utilizados por terceros para desarrollar nuevas investigaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los microbios que viven en el suelo podr\u00edan ser una fuente de energ\u00eda para los sensores subterr\u00e1neos utilizados en la agricultura de precisi\u00f3n y las infraestructuras sostenibles. La novedad la ha propuesto un equipo de investigadores de la Universidad Northwestern de Estados Unidos, que ha desarrollado una nueva pila de combustible que podr\u00eda convertirse en&#8230;<\/p>\n","protected":false},"featured_media":15098,"comment_status":"closed","ping_status":"closed","template":"","format":[],"category":[250],"tags":[],"company":[],"topic":[],"class_list":["post-15281","articles","type-articles","status-publish","has-post-thumbnail","hentry","category-monitoreo-de-recursos"],"acf":[],"_links":{"self":[{"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/articles\/15281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/articles"}],"about":[{"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/types\/articles"}],"replies":[{"embeddable":true,"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/comments?post=15281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/media\/15098"}],"wp:attachment":[{"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/media?parent=15281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/category?post=15281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/tags?post=15281"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/format?post=15281"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/company?post=15281"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/network-king.net\/es\/wp-json\/wp\/v2\/topic?post=15281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}